{"id":17321,"date":"2026-07-13T09:15:04","date_gmt":"2026-07-13T09:15:04","guid":{"rendered":"https:\/\/nsf.pt\/?p=17321"},"modified":"2026-07-13T09:59:03","modified_gmt":"2026-07-13T09:59:03","slug":"cim-peninsula-de-setubal-uma-comunidade","status":"publish","type":"post","link":"https:\/\/nsf.pt\/index.php\/2026\/07\/13\/cim-peninsula-de-setubal-uma-comunidade\/","title":{"rendered":"CIM Pen\u00ednsula de Set\u00fabal, uma comunidade?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Para que serve uma organiza\u00e7\u00e3o de car\u00e1cter intermunicipal?<\/h2>\n\n\n\n<p class=\"\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"716\" height=\"376\" src=\"https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/Joao-Barreta.jpg\" alt=\"\" class=\"wp-image-17322\" style=\"aspect-ratio:1.9042553191489362;width:229px;height:auto\" srcset=\"https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/Joao-Barreta.jpg 716w, https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/Joao-Barreta-300x158.jpg 300w\" sizes=\"(max-width: 716px) 100vw, 716px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Por Jo\u00e3o Barreta<\/h2>\n\n\n\n<p class=\"\">Para aeroporto, terceira travessia do Tejo e fundos comunit\u00e1rios uma comunidade concentrada e concertada, j\u00e1 para o abastecimento de \u00e1gua e a recolha de res\u00edduos, uma CIM desconcertada e desconcentrada.<\/p>\n\n\n\n<p class=\"\">A CIM Pen\u00ednsula de Set\u00fabal foi criada recentemente, pelo que as popula\u00e7\u00f5es ainda n\u00e3o ter\u00e3o a percep\u00e7\u00e3o da import\u00e2ncia e do papel que tal organiza\u00e7\u00e3o pode e deve assumir.<br>Assim sendo, os primeiros passos da exist\u00eancia da CIM ser\u00e3o cruciais.<\/p>\n\n\n\n<p class=\"\">A recente &#8220;crise da \u00e1gua&#8221; no concelho de Almada, a &#8220;crise do lixo&#8221; em v\u00e1rios concelhos, para citar apenas estas duas situa\u00e7\u00f5es, n\u00e3o seriam raz\u00f5es mais do que suficientes para a Comunidade &#8220;pensar local e agir global&#8221; e\/ou vice-versa?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"\">A ideia de &#8220;Comunidade&#8221; tem de passar para a &#8230; comunidade.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"\">Se Almada tem um problema grave com o abastecimento de \u00e1gua, os restantes membros da Comunidade solidarizam-se com Almada e prestam toda a ajuda poss\u00edvel. Ou n\u00e3o?<\/p>\n\n\n\n<p class=\"\">Se um munic\u00edpio da Comunidade tem um problema com a recolha do lixo, os outros membros prestam apoio, cedendo viaturas, por exemplo, ou n\u00e3o.<\/p>\n\n\n\n<p class=\"\">Ainda \u00e9 cedo, \u00e9 certo, mas nesta fase, perante problemas desta magnitude, a percep\u00e7\u00e3o das popula\u00e7\u00f5es que comp\u00f5em os municipios, que integram a Comunidade, em rela\u00e7\u00e3o \u00e0 nova CIM n\u00e3o poder ser &#8230; indiferente.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"\">Afinal o que se entende por Comunidade? Para que serve uma &#8220;organiza\u00e7\u00e3o&#8221; de car\u00e1cter InterMunicipal?<\/p>\n<\/blockquote>\n\n\n\n<p class=\"\">N\u00e3o ser\u00e1 necess\u00e1rio ler-se todos os manuais, mas qualquer dicion\u00e1rio j\u00e1 ser\u00e1 uma primeira ajuda.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Nem um &#8230; &#8220;comunicadozito&#8221; por parte da &#8230; Comunidade dirigido \u00e0 &#8230; comunidade?<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Para que serve uma organiza\u00e7\u00e3o de car\u00e1cter intermunicipal? Por Jo\u00e3o Barreta Para aeroporto, terceira travessia&#8230;<\/p>\n","protected":false},"author":2,"featured_media":17323,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3,459,442],"tags":[698],"featured_image_urls":{"full":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"thumbnail":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada-150x150.jpg",150,150,true],"medium":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada-300x217.jpg",300,217,true],"medium_large":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"large":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"1536x1536":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"2048x2048":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"covernews-slider-full":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"covernews-slider-center":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"covernews-featured":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"covernews-medium":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false],"covernews-medium-square":["https:\/\/nsf.pt\/wp-content\/uploads\/2026\/07\/cmalmada.jpg",337,244,false]},"author_info":{"info":["Carlos Ribeiro"]},"category_info":"<a href=\"https:\/\/nsf.pt\/index.php\/category\/cooperacao\/\" rel=\"category tag\">COOPERA\u00c7\u00c3O<\/a> <a href=\"https:\/\/nsf.pt\/index.php\/category\/curtas\/\" rel=\"category tag\">CURTAS<\/a> <a href=\"https:\/\/nsf.pt\/index.php\/category\/de-viva-voz\/\" rel=\"category tag\">DE VIVA VOZ<\/a>","tag_info":"DE VIVA VOZ","comment_count":"0","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/posts\/17321"}],"collection":[{"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/comments?post=17321"}],"version-history":[{"count":3,"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/posts\/17321\/revisions"}],"predecessor-version":[{"id":17331,"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/posts\/17321\/revisions\/17331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/media\/17323"}],"wp:attachment":[{"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/media?parent=17321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/categories?post=17321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nsf.pt\/index.php\/wp-json\/wp\/v2\/tags?post=17321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}